{"id":10822,"date":"2023-10-31T03:34:38","date_gmt":"2023-10-30T18:34:38","guid":{"rendered":"http:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e3%82%a2%e3%83%ab%e3%83%9f%e7%bc%b6%e6%96%b0%e5%86%8d%e7%94%9f%e6%96%b9%e6%b3%95\/"},"modified":"2023-10-31T03:34:38","modified_gmt":"2023-10-30T18:34:38","slug":"%e3%82%a2%e3%83%ab%e3%83%9f%e7%bc%b6%e6%96%b0%e5%86%8d%e7%94%9f%e6%96%b9%e6%b3%95","status":"publish","type":"post","link":"https:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e3%82%a2%e3%83%ab%e3%83%9f%e7%bc%b6%e6%96%b0%e5%86%8d%e7%94%9f%e6%96%b9%e6%b3%95\/","title":{"rendered":"\u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5"},"content":{"rendered":"<p>\u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5\u6280\u8853\u8ad6\u6587\u30fb\u6280\u8853\u5831\u544a\u30fb\u6280\u8853\u8cc7\u6599\u30fb\u7814\u7a76\u30ce\u30fc\u30c8\u30fb\u7279\u5225\u5bc4\u7a3f\u30fb\u8cc7\u6599[T]199712\u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5New Recycling System for Used Beverage Can\u5bfa\u7530\u4fee(\u65e5\u672c\u92f3\u9020\uff08\u682a\uff09)\u3001\u6709\u65b9\u548c\u7fa9(\u65e5\u672c\u92f3\u9020\uff08\u682a\uff09)New Recycling System for Used Beverage Can, \u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5, \u5ec3\u30a2\u30eb\u30df\u30cb\u30a6\u30e0\u7f36\u3001\u518d\u751f\u65b9\u6cd5\u3001\u975e\u6eb6\u89e3\u3001\u7814\u78e8Vol.69-1025\u6280\u8853\u8ad6\u6587\u30fb\u6280\u8853\u5831\u544a\u30fb\u6280\u8853\u8cc7\u6599\u30fb\u7814\u7a76\u30ce\u30fc\u30c8\u30fb\u7279\u5225\u5bc4\u7a3f\u30fb\u8cc7\u6599[T]n10614<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5\u6280\u8853\u8ad6\u6587\u30fb\u6280\u8853\u5831\u544a\u30fb\u6280\u8853\u8cc7\u6599\u30fb\u7814\u7a76\u30ce\u30fc\u30c8\u30fb\u7279\u5225\u5bc4\u7a3f\u30fb\u8cc7\u6599[T]199712\u30a2\u30eb\u30df\u7f36\u65b0\u518d\u751f\u65b9\u6cd5New Recycling System for Used Beverage Can\u5bfa\u7530\u4fee(\u65e5\u672c\u92f3\u9020\uff08\u682a\uff09)\u3001 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"vkexunit_cta_each_option":"","footnotes":""},"categories":[1],"tags":[],"bunrui":[9],"class_list":["post-10822","post","type-post","status-publish","format-standard","hentry","category-bunken","bunrui-9"],"acf":[],"_links":{"self":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/10822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/comments?post=10822"}],"version-history":[{"count":0,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/10822\/revisions"}],"wp:attachment":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/media?parent=10822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/categories?post=10822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/tags?post=10822"},{"taxonomy":"bunrui","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/bunrui?post=10822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}