{"id":10838,"date":"2023-10-31T03:34:39","date_gmt":"2023-10-30T18:34:39","guid":{"rendered":"http:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e3%83%ac%e3%83%bc%e3%82%b6%e3%82%af%e3%83%a9%e3%83%83%e3%83%87%e3%82%a3%e3%83%b3%e3%82%b0%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e6%ba%b6%e8%9e%8d%e7%8f%be%e8%b1%a1%e3%81%ae%e6%9c%89%e9%99%90%e8%a6%81\/"},"modified":"2023-10-31T03:34:39","modified_gmt":"2023-10-30T18:34:39","slug":"%e3%83%ac%e3%83%bc%e3%82%b6%e3%82%af%e3%83%a9%e3%83%83%e3%83%87%e3%82%a3%e3%83%b3%e3%82%b0%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e6%ba%b6%e8%9e%8d%e7%8f%be%e8%b1%a1%e3%81%ae%e6%9c%89%e9%99%90%e8%a6%81","status":"publish","type":"post","link":"https:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e3%83%ac%e3%83%bc%e3%82%b6%e3%82%af%e3%83%a9%e3%83%83%e3%83%87%e3%82%a3%e3%83%b3%e3%82%b0%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e6%ba%b6%e8%9e%8d%e7%8f%be%e8%b1%a1%e3%81%ae%e6%9c%89%e9%99%90%e8%a6%81\/","title":{"rendered":"\u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790"},"content":{"rendered":"<p>\u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]199801\u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790FEM Analysis of Melting Behavior in Laser Cladding\u963f\u90e8\u53f2\u679d(\u5927\u962a\u5927\u5b66)\u3001\u5409\u7559\u5f70\u5b8f(\u5927\u962a\u5927\u5b66)\u3001\u5c0f\u5742\u7530\u5b8f\u9020(\u5927\u962a\u5927\u5b66)\u3001\u5869\u898b\u8aa0\u898f(\u5927\u962a\u5927\u5b66)FEM Analysis of Melting Behavior in Laser Cladding, \u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790, laser cladding, FEM, fusion, adhesivenessVol.70-0040\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]n10630<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]199801\u30ec\u30fc\u30b6\u30af\u30e9\u30c3\u30c7\u30a3\u30f3\u30b0\u306b\u304a\u3051\u308b\u6eb6\u878d\u73fe\u8c61\u306e\u6709\u9650\u8981\u7d20\u89e3\u6790FEM Analysis of Melting Behavior in Laser Cl [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"vkexunit_cta_each_option":"","footnotes":""},"categories":[1],"tags":[],"bunrui":[5],"class_list":["post-10838","post","type-post","status-publish","format-standard","hentry","category-bunken","bunrui-p"],"acf":[],"_links":{"self":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/10838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/comments?post=10838"}],"version-history":[{"count":0,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/10838\/revisions"}],"wp:attachment":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/media?parent=10838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/categories?post=10838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/tags?post=10838"},{"taxonomy":"bunrui","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/bunrui?post=10838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}