{"id":11021,"date":"2023-10-31T03:34:51","date_gmt":"2023-10-30T18:34:51","guid":{"rendered":"http:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e5%a4%a7%e5%9e%8b%e3%83%88%e3%83%a9%e3%83%b3%e3%82%b9%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e3%82%b1%e3%83%bc%e3%82%b9%e3%81%ae%e4%b8%8d%e8%89%af%e4%bd%8e%e6%b8%9b\/"},"modified":"2023-10-31T03:34:51","modified_gmt":"2023-10-30T18:34:51","slug":"%e5%a4%a7%e5%9e%8b%e3%83%88%e3%83%a9%e3%83%b3%e3%82%b9%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e3%82%b1%e3%83%bc%e3%82%b9%e3%81%ae%e4%b8%8d%e8%89%af%e4%bd%8e%e6%b8%9b","status":"publish","type":"post","link":"https:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e5%a4%a7%e5%9e%8b%e3%83%88%e3%83%a9%e3%83%b3%e3%82%b9%e3%83%9f%e3%83%83%e3%82%b7%e3%83%a7%e3%83%b3%e3%82%b1%e3%83%bc%e3%82%b9%e3%81%ae%e4%b8%8d%e8%89%af%e4%bd%8e%e6%b8%9b\/","title":{"rendered":"\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b"},"content":{"rendered":"<p>\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b\u73fe\u5834\u6280\u8853\u95a2\u9023[K]199907\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b\u9234\u6728\u6b63\u5e78(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u690d\u7530\u885b(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u5ca1\u672c\u6b63\u7f8e(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u9ad8\u6a4b\u5149\u592b(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u9752\u91ce\u6b63\u592b(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u5c71\u5185\u4ec1(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b, \u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u3001\u4e0d\u826f\u4f4e\u6e1bVol.71-0493\u73fe\u5834\u6280\u8853\u95a2\u9023[K]n10813<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b\u73fe\u5834\u6280\u8853\u95a2\u9023[K]199907\u5927\u578b\u30c8\u30e9\u30f3\u30b9\u30df\u30c3\u30b7\u30e7\u30f3\u30b1\u30fc\u30b9\u306e\u4e0d\u826f\u4f4e\u6e1b\u9234\u6728\u6b63\u5e78(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u690d\u7530\u885b(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u5ca1\u672c\u6b63\u7f8e(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u9ad8\u6a4b\u5149\u592b(\u65ed\u30c6\u30c3\u30af\uff08\u682a\uff09)\u3001\u9752\u91ce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"vkexunit_cta_each_option":"","footnotes":""},"categories":[1],"tags":[],"bunrui":[6],"class_list":["post-11021","post","type-post","status-publish","format-standard","hentry","category-bunken","bunrui-k"],"acf":[],"_links":{"self":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/11021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/comments?post=11021"}],"version-history":[{"count":0,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/11021\/revisions"}],"wp:attachment":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/media?parent=11021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/categories?post=11021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/tags?post=11021"},{"taxonomy":"bunrui","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/bunrui?post=11021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}