{"id":11045,"date":"2023-10-31T03:34:53","date_gmt":"2023-10-30T18:34:53","guid":{"rendered":"http:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e6%b0%b4%e7%92%b0%e5%a2%83%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%aa%e3%83%bc%e3%82%b9%e3%83%86%e3%83%b3%e3%83%91%e7%90%83%e7%8a%b6%e9%bb%92%e9%89%9b%e9%8b%b3%e9%89%84%e3%81%ae%e7%96%b2%e3%82%8c\/"},"modified":"2023-10-31T03:34:53","modified_gmt":"2023-10-30T18:34:53","slug":"%e6%b0%b4%e7%92%b0%e5%a2%83%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%aa%e3%83%bc%e3%82%b9%e3%83%86%e3%83%b3%e3%83%91%e7%90%83%e7%8a%b6%e9%bb%92%e9%89%9b%e9%8b%b3%e9%89%84%e3%81%ae%e7%96%b2%e3%82%8c","status":"publish","type":"post","link":"https:\/\/jfs.or.jp\/bunken-search\/2023\/10\/31\/%e6%b0%b4%e7%92%b0%e5%a2%83%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%aa%e3%83%bc%e3%82%b9%e3%83%86%e3%83%b3%e3%83%91%e7%90%83%e7%8a%b6%e9%bb%92%e9%89%9b%e9%8b%b3%e9%89%84%e3%81%ae%e7%96%b2%e3%82%8c\/","title":{"rendered":"\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027"},"content":{"rendered":"<p>\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]199910\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027Fatigue Properties of Austempered Spheroidal Graphite Cast Iron in Water Environment\u7530\u4e2d\u96c4\u4e00(\u5ba4\u862d\u5de5\u696d\u5927\u5b66)\u3001\u8521\u5553\u821f(\u5ba4\u862d\u5de5\u696d\u5927\u5b66)\u3001\u9577\u8239\u5eb7\u88d5(\u5ba4\u862d\u5de5\u696d\u5927\u5b66)austempered spheroidal graphite cast iron (ADI), ferritic spheroidal graphite cast iron, exposure to water, fatigue strength, corrosion pit, corrosion fatigue\uff1b\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027Vol.71-0698\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]n10837<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027\u7814\u7a76\u8ad6\u6587\u30fb\u8ad6\u8aac[P]199910\u6c34\u74b0\u5883\u306b\u304a\u3051\u308b\u30aa\u30fc\u30b9\u30c6\u30f3\u30d1\u7403\u72b6\u9ed2\u925b\u92f3\u9244\u306e\u75b2\u308c\u7279\u6027Fatigue Properties of Austempered Spheroidal G [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"vkexunit_cta_each_option":"","footnotes":""},"categories":[1],"tags":[],"bunrui":[5],"class_list":["post-11045","post","type-post","status-publish","format-standard","hentry","category-bunken","bunrui-p"],"acf":[],"_links":{"self":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/11045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/comments?post=11045"}],"version-history":[{"count":0,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/posts\/11045\/revisions"}],"wp:attachment":[{"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/media?parent=11045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/categories?post=11045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/tags?post=11045"},{"taxonomy":"bunrui","embeddable":true,"href":"https:\/\/jfs.or.jp\/bunken-search\/wp-json\/wp\/v2\/bunrui?post=11045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}